{"id":25,"date":"2021-10-09T22:07:52","date_gmt":"2021-10-09T21:07:52","guid":{"rendered":"http:\/\/escamarlansdepalau.com\/?page_id=25"},"modified":"2021-12-05T21:31:30","modified_gmt":"2021-12-05T20:31:30","slug":"fotografies","status":"publish","type":"page","link":"https:\/\/escamarlansdepalau.com\/index.php\/fotografies\/","title":{"rendered":"Fotografies"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"990\" height=\"938\" src=\"https:\/\/i0.wp.com\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-27-52.jpg?resize=990%2C938&#038;ssl=1\" alt=\"\" class=\"wp-image-46\" srcset=\"https:\/\/i0.wp.com\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-27-52.jpg?resize=1024%2C970&amp;ssl=1 1024w, https:\/\/i0.wp.com\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-27-52.jpg?resize=300%2C284&amp;ssl=1 300w, https:\/\/i0.wp.com\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-27-52.jpg?resize=768%2C728&amp;ssl=1 768w, https:\/\/i0.wp.com\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-27-52.jpg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 990px) 100vw, 990px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"990\" height=\"938\" src=\"https:\/\/i0.wp.com\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-28-06.jpg?resize=990%2C938&#038;ssl=1\" alt=\"\" class=\"wp-image-48\" srcset=\"https:\/\/i0.wp.com\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-28-06.jpg?resize=1024%2C970&amp;ssl=1 1024w, https:\/\/i0.wp.com\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-28-06.jpg?resize=300%2C284&amp;ssl=1 300w, https:\/\/i0.wp.com\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-28-06.jpg?resize=768%2C728&amp;ssl=1 768w, https:\/\/i0.wp.com\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-28-06.jpg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 990px) 100vw, 990px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"990\" height=\"938\" src=\"https:\/\/i0.wp.com\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-28-08.jpg?resize=990%2C938&#038;ssl=1\" alt=\"\" class=\"wp-image-49\" srcset=\"https:\/\/i0.wp.com\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-28-08.jpg?resize=1024%2C970&amp;ssl=1 1024w, https:\/\/i0.wp.com\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-28-08.jpg?resize=300%2C284&amp;ssl=1 300w, https:\/\/i0.wp.com\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-28-08.jpg?resize=768%2C728&amp;ssl=1 768w, https:\/\/i0.wp.com\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-28-08.jpg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 990px) 100vw, 990px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"990\" height=\"938\" src=\"https:\/\/i0.wp.com\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-28-11.jpg?resize=990%2C938&#038;ssl=1\" alt=\"\" class=\"wp-image-50\" srcset=\"https:\/\/i0.wp.com\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-28-11.jpg?resize=1024%2C970&amp;ssl=1 1024w, https:\/\/i0.wp.com\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-28-11.jpg?resize=300%2C284&amp;ssl=1 300w, https:\/\/i0.wp.com\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-28-11.jpg?resize=768%2C728&amp;ssl=1 768w, https:\/\/i0.wp.com\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-28-11.jpg?w=1182&amp;ssl=1 1182w\" sizes=\"auto, (max-width: 990px) 100vw, 990px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"990\" height=\"938\" src=\"https:\/\/i0.wp.com\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-28-13.jpg?resize=990%2C938&#038;ssl=1\" alt=\"\" class=\"wp-image-51\" srcset=\"https:\/\/i0.wp.com\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-28-13.jpg?resize=1024%2C970&amp;ssl=1 1024w, https:\/\/i0.wp.com\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-28-13.jpg?resize=300%2C284&amp;ssl=1 300w, https:\/\/i0.wp.com\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-28-13.jpg?resize=768%2C727&amp;ssl=1 768w, https:\/\/i0.wp.com\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-28-13.jpg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 990px) 100vw, 990px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-25","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fotografies - Escamarlans de Palau<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/escamarlansdepalau.com\/index.php\/fotografies\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fotografies - Escamarlans de Palau\" \/>\n<meta property=\"og:url\" content=\"https:\/\/escamarlansdepalau.com\/index.php\/fotografies\/\" \/>\n<meta property=\"og:site_name\" content=\"Escamarlans de Palau\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-05T20:31:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-27-52-1024x970.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/escamarlansdepalau.com\/index.php\/fotografies\/\",\"url\":\"https:\/\/escamarlansdepalau.com\/index.php\/fotografies\/\",\"name\":\"Fotografies - Escamarlans de Palau\",\"isPartOf\":{\"@id\":\"https:\/\/escamarlansdepalau.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/escamarlansdepalau.com\/index.php\/fotografies\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/escamarlansdepalau.com\/index.php\/fotografies\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-27-52-1024x970.jpg\",\"datePublished\":\"2021-10-09T21:07:52+00:00\",\"dateModified\":\"2021-12-05T20:31:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/escamarlansdepalau.com\/index.php\/fotografies\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/escamarlansdepalau.com\/index.php\/fotografies\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/escamarlansdepalau.com\/index.php\/fotografies\/#primaryimage\",\"url\":\"https:\/\/i0.wp.com\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-27-52.jpg?fit=1280%2C1213&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-27-52.jpg?fit=1280%2C1213&ssl=1\",\"width\":1280,\"height\":1213},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/escamarlansdepalau.com\/index.php\/fotografies\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/escamarlansdepalau.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fotografies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/escamarlansdepalau.com\/#website\",\"url\":\"https:\/\/escamarlansdepalau.com\/\",\"name\":\"Escamarlans de Palau\",\"description\":\"Grup d&#039;havaneres i can\u00e7\u00f3 de taverna\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/escamarlansdepalau.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fotografies - Escamarlans de Palau","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/escamarlansdepalau.com\/index.php\/fotografies\/","og_locale":"ca_ES","og_type":"article","og_title":"Fotografies - Escamarlans de Palau","og_url":"https:\/\/escamarlansdepalau.com\/index.php\/fotografies\/","og_site_name":"Escamarlans de Palau","article_modified_time":"2021-12-05T20:31:30+00:00","og_image":[{"url":"https:\/\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-27-52-1024x970.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/escamarlansdepalau.com\/index.php\/fotografies\/","url":"https:\/\/escamarlansdepalau.com\/index.php\/fotografies\/","name":"Fotografies - Escamarlans de Palau","isPartOf":{"@id":"https:\/\/escamarlansdepalau.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/escamarlansdepalau.com\/index.php\/fotografies\/#primaryimage"},"image":{"@id":"https:\/\/escamarlansdepalau.com\/index.php\/fotografies\/#primaryimage"},"thumbnailUrl":"https:\/\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-27-52-1024x970.jpg","datePublished":"2021-10-09T21:07:52+00:00","dateModified":"2021-12-05T20:31:30+00:00","breadcrumb":{"@id":"https:\/\/escamarlansdepalau.com\/index.php\/fotografies\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/escamarlansdepalau.com\/index.php\/fotografies\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/escamarlansdepalau.com\/index.php\/fotografies\/#primaryimage","url":"https:\/\/i0.wp.com\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-27-52.jpg?fit=1280%2C1213&ssl=1","contentUrl":"https:\/\/i0.wp.com\/escamarlansdepalau.com\/wp-content\/uploads\/2021\/12\/photo_2021-12-05_21-27-52.jpg?fit=1280%2C1213&ssl=1","width":1280,"height":1213},{"@type":"BreadcrumbList","@id":"https:\/\/escamarlansdepalau.com\/index.php\/fotografies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/escamarlansdepalau.com\/"},{"@type":"ListItem","position":2,"name":"Fotografies"}]},{"@type":"WebSite","@id":"https:\/\/escamarlansdepalau.com\/#website","url":"https:\/\/escamarlansdepalau.com\/","name":"Escamarlans de Palau","description":"Grup d&#039;havaneres i can\u00e7\u00f3 de taverna","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/escamarlansdepalau.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/escamarlansdepalau.com\/index.php\/wp-json\/wp\/v2\/pages\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/escamarlansdepalau.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/escamarlansdepalau.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/escamarlansdepalau.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/escamarlansdepalau.com\/index.php\/wp-json\/wp\/v2\/comments?post=25"}],"version-history":[{"count":2,"href":"https:\/\/escamarlansdepalau.com\/index.php\/wp-json\/wp\/v2\/pages\/25\/revisions"}],"predecessor-version":[{"id":52,"href":"https:\/\/escamarlansdepalau.com\/index.php\/wp-json\/wp\/v2\/pages\/25\/revisions\/52"}],"wp:attachment":[{"href":"https:\/\/escamarlansdepalau.com\/index.php\/wp-json\/wp\/v2\/media?parent=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}